{"id":1381,"date":"2025-08-18T18:19:19","date_gmt":"2025-08-18T18:19:19","guid":{"rendered":"https:\/\/de-stainless.de\/product\/open-trolleys-for-trays-single-front-access\/"},"modified":"2025-11-13T13:41:50","modified_gmt":"2025-11-13T13:41:50","slug":"offene-transportwagen-fur-tabletts-einseitiger-frontzugang","status":"publish","type":"product","link":"https:\/\/de-stainless.de\/tr\/shop\/transportwagen\/offene-transportwagen-fur-tabletts-einseitiger-frontzugang\/","title":{"rendered":"Tek tarafl\u0131 \u00f6n eri\u015fimli a\u00e7\u0131k tepsi ta\u015f\u0131ma arabalar\u0131"},"content":{"rendered":"<p>Offener Transportwagen mit einseitigem Frontzugang, ideal f\u00fcr schnelles Ein- und Aussetzen von Tabletts in engen G\u00e4ngen. Der Rahmen besteht aus AISI 304 Edelstahlrohren und ist offen gestaltet, sodass die Sicht auf den Inhalt jederzeit gegeben ist.<\/p>\n<p>Der Wagen verf\u00fcgt \u00fcber einseitige F\u00fchrungsschienen, leicht laufende Lenkrollen mit Bremsen sowie optional anbringbare Seitenbegrenzungen oder Halter f\u00fcr Beschriftungen.<\/p>","protected":false},"excerpt":{"rendered":"<p>\u00d6n eri\u015fimli a\u00e7\u0131k paslanmaz \u00e7elik ta\u015f\u0131ma arabas\u0131; tek tarafl\u0131 k\u0131zaklar, ak\u0131c\u0131 d\u00f6ner tekerlekler ve iste\u011fe ba\u011fl\u0131 yan s\u0131n\u0131rl\u0131klar veya etiket tutucular ile.<\/p>","protected":false},"featured_media":1246,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[64],"product_tag":[],"class_list":["post-1381","product","type-product","status-publish","has-post-thumbnail","product_cat-transportwagen","first","instock","shipping-taxable","product-type-simple"],"acf":[],"_links":{"self":[{"href":"https:\/\/de-stainless.de\/tr\/wp-json\/wp\/v2\/product\/1381","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/de-stainless.de\/tr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/de-stainless.de\/tr\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/de-stainless.de\/tr\/wp-json\/wp\/v2\/media\/1246"}],"wp:attachment":[{"href":"https:\/\/de-stainless.de\/tr\/wp-json\/wp\/v2\/media?parent=1381"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/de-stainless.de\/tr\/wp-json\/wp\/v2\/product_brand?post=1381"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/de-stainless.de\/tr\/wp-json\/wp\/v2\/product_cat?post=1381"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/de-stainless.de\/tr\/wp-json\/wp\/v2\/product_tag?post=1381"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}