{"id":1272,"date":"2025-08-18T18:50:12","date_gmt":"2025-08-18T18:50:12","guid":{"rendered":"https:\/\/de-stainless.de\/product\/work-table-with-sliding-doors-and-drawer-unit\/"},"modified":"2025-11-13T12:42:26","modified_gmt":"2025-11-13T12:42:26","slug":"arbeitstisch-mit-schiebeturen-und-schubladeneinheit","status":"publish","type":"product","link":"https:\/\/de-stainless.de\/it\/shop\/arbeitstische\/arbeitstisch-mit-schiebeturen-und-schubladeneinheit\/","title":{"rendered":"Tavolo da lavoro con porte scorrevoli e cassettiera"},"content":{"rendered":"<p>Questo modello combina un mobile inferiore chiuso con ante scorrevoli fluide e un\u2019unit\u00e0 cassetti integrata per utensili, posate o materiali di consumo. Il piano di lavoro profondo 600 mm in acciaio inox AISI 304 offre una superficie robusta e igienica, mentre i cassetti mantengono gli utensili pi\u00f9 utilizzati sempre a portata di mano. L\u2019area del mobile chiuso protegge gli oggetti pi\u00f9 grandi da polvere e schizzi. Progettato per un uso intensivo nelle cucine professionali, il tavolo si distingue per la struttura saldata, gli angoli arrotondati e i piedini regolabili che garantiscono un livellamento perfetto e una pulizia agevole.<\/p>","protected":false},"excerpt":{"rendered":"<p>Tavolo da lavoro in acciaio inox con ante scorrevoli e unit\u00e0 cassetti \u2013 stabile, igienico e funzionale per cucine professionali.<\/p>","protected":false},"featured_media":1137,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[58],"product_tag":[],"class_list":["post-1272","product","type-product","status-publish","has-post-thumbnail","product_cat-arbeitstische","first","instock","shipping-taxable","product-type-simple"],"acf":[],"_links":{"self":[{"href":"https:\/\/de-stainless.de\/it\/wp-json\/wp\/v2\/product\/1272","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/de-stainless.de\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/de-stainless.de\/it\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/de-stainless.de\/it\/wp-json\/wp\/v2\/media\/1137"}],"wp:attachment":[{"href":"https:\/\/de-stainless.de\/it\/wp-json\/wp\/v2\/media?parent=1272"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/de-stainless.de\/it\/wp-json\/wp\/v2\/product_brand?post=1272"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/de-stainless.de\/it\/wp-json\/wp\/v2\/product_cat?post=1272"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/de-stainless.de\/it\/wp-json\/wp\/v2\/product_tag?post=1272"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}