{"id":1381,"date":"2025-08-18T18:19:19","date_gmt":"2025-08-18T18:19:19","guid":{"rendered":"https:\/\/de-stainless.de\/product\/open-trolleys-for-trays-single-front-access\/"},"modified":"2025-11-13T13:41:50","modified_gmt":"2025-11-13T13:41:50","slug":"offene-transportwagen-fur-tabletts-einseitiger-frontzugang","status":"publish","type":"product","link":"https:\/\/de-stainless.de\/fr\/shop\/transportwagen\/offene-transportwagen-fur-tabletts-einseitiger-frontzugang\/","title":{"rendered":"Chariots de transport ouverts pour plateaux, acc\u00e8s frontal d\u2019un seul c\u00f4t\u00e9"},"content":{"rendered":"<p>Offener Transportwagen mit einseitigem Frontzugang, ideal f\u00fcr schnelles Ein- und Aussetzen von Tabletts in engen G\u00e4ngen. Der Rahmen besteht aus AISI 304 Edelstahlrohren und ist offen gestaltet, sodass die Sicht auf den Inhalt jederzeit gegeben ist.<\/p>\n<p>Der Wagen verf\u00fcgt \u00fcber einseitige F\u00fchrungsschienen, leicht laufende Lenkrollen mit Bremsen sowie optional anbringbare Seitenbegrenzungen oder Halter f\u00fcr Beschriftungen.<\/p>","protected":false},"excerpt":{"rendered":"<p>Chariot de transport ouvert en acier inoxydable avec acc\u00e8s frontal, glissi\u00e8res unilat\u00e9rales, roulettes pivotantes fluides et options de rebords lat\u00e9raux ou porte-\u00e9tiquettes.<\/p>","protected":false},"featured_media":1246,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[64],"product_tag":[],"class_list":["post-1381","product","type-product","status-publish","has-post-thumbnail","product_cat-transportwagen","first","instock","shipping-taxable","product-type-simple"],"acf":[],"_links":{"self":[{"href":"https:\/\/de-stainless.de\/fr\/wp-json\/wp\/v2\/product\/1381","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/de-stainless.de\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/de-stainless.de\/fr\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/de-stainless.de\/fr\/wp-json\/wp\/v2\/media\/1246"}],"wp:attachment":[{"href":"https:\/\/de-stainless.de\/fr\/wp-json\/wp\/v2\/media?parent=1381"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/de-stainless.de\/fr\/wp-json\/wp\/v2\/product_brand?post=1381"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/de-stainless.de\/fr\/wp-json\/wp\/v2\/product_cat?post=1381"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/de-stainless.de\/fr\/wp-json\/wp\/v2\/product_tag?post=1381"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}