{"id":1288,"date":"2025-08-18T18:07:12","date_gmt":"2025-08-18T18:07:12","guid":{"rendered":"https:\/\/de-stainless.de\/product\/base-unit-with-sliding-doors-and-drawers\/"},"modified":"2025-11-13T13:51:06","modified_gmt":"2025-11-13T13:51:06","slug":"unterschrank-mit-schiebeturen-und-schubladen","status":"publish","type":"product","link":"https:\/\/de-stainless.de\/fr\/shop\/arbeitstische\/unterschrank-mit-schiebeturen-und-schubladen\/","title":{"rendered":"Meuble bas avec portes coulissantes et tiroirs"},"content":{"rendered":"<p>Zentrale Unterschrank-Ausf\u00fchrung ohne Aufkantung, kombiniert ein ger\u00e4umiges Schiebet\u00fcrfach mit einem integrierten Schubladenelement. Hergestellt aus AISI 304 Edelstahl, 700 mm tief, f\u00fcr den intensiven professionellen Einsatz. Die T\u00fcren laufen auf platzsparenden Schienen, w\u00e4hrend die Schubladen h\u00e4ufig ben\u00f6tigte Utensilien griffbereit halten. Verschwei\u00dfte Ecken und glatte Oberfl\u00e4chen erleichtern die Reinigung und gew\u00e4hrleisten Hygiene.<\/p>\n<p>Optional kann ein Innenfach im Schrank erg\u00e4nzt werden. H\u00f6henverstellbare Edelstahlf\u00fc\u00dfe erm\u00f6glichen eine exakte Nivellierung auf jedem Untergrund.<\/p>","protected":false},"excerpt":{"rendered":"<p>Meuble bas central en acier inoxydable AISI 304, profondeur 700 mm, avec compartiment \u00e0 porte coulissante et \u00e9l\u00e9ment tiroir, ar\u00eates arrondies, facile \u00e0 nettoyer et pieds r\u00e9glables en hauteur.<\/p>","protected":false},"featured_media":1153,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[58],"product_tag":[],"class_list":["post-1288","product","type-product","status-publish","has-post-thumbnail","product_cat-arbeitstische","first","instock","shipping-taxable","product-type-simple"],"acf":[],"_links":{"self":[{"href":"https:\/\/de-stainless.de\/fr\/wp-json\/wp\/v2\/product\/1288","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/de-stainless.de\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/de-stainless.de\/fr\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/de-stainless.de\/fr\/wp-json\/wp\/v2\/media\/1153"}],"wp:attachment":[{"href":"https:\/\/de-stainless.de\/fr\/wp-json\/wp\/v2\/media?parent=1288"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/de-stainless.de\/fr\/wp-json\/wp\/v2\/product_brand?post=1288"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/de-stainless.de\/fr\/wp-json\/wp\/v2\/product_cat?post=1288"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/de-stainless.de\/fr\/wp-json\/wp\/v2\/product_tag?post=1288"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}